
{"id":93083,"date":"2024-10-07T16:06:37","date_gmt":"2024-10-07T15:06:37","guid":{"rendered":"https:\/\/smeclimatehub.org\/?page_id=93083"},"modified":"2025-11-04T21:24:58","modified_gmt":"2025-11-04T20:24:58","slug":"cadeias-de-abastecimento","status":"publish","type":"page","link":"https:\/\/smeclimatehub.org\/pt-br\/espaco-de-acao\/cadeias-de-abastecimento\/","title":{"rendered":"Cadeias de abastecimento"},"content":{"rendered":"        <section class=\"action-space-blocks align-content-top light content-block\">\n            <div class=\"container\">\n                <div class=\"area-blocks\">\n                    <div class=\"area-block\">\n                                                <div class=\"stage\"><div class=\"number\">01<\/div><div class=\"title\">Come\u00e7ar<\/div><div class=\"stage-info\"><img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/beginIcon.svg\"> Desenvolver uma compreens\u00e3o<\/div><\/div>                                                                        <div class=\"outer-blocks swiper\">\n                            <div class=\"blocks-wrapper swiper-wrapper\">\n                                                                            <div class=\"block resource swiper-slide guide\">\n                                                <div class=\"inner\">\n                                                    <div class=\"image\">\n                                                        <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/workWithSuppliers-1-scaled-1.jpg\">\n                                                                                                                                                                    <\/div>\n                                                    <div class=\"text\">\n                                                        <div class=\"label\">Guia de A\u00e7\u00e3o<\/div>                                                        <h3 class=\"title\">Engajar fornecedores para reduzir as emiss\u00f5es<\/h3>\n                                                        <p><p>Adote medidas para trabalhar com seus fornecedores a fim de reduzir as emiss\u00f5es em toda a sua cadeia de valor.<\/p>\n<\/p>\n                                                    <\/div>\n\n                                                    <span class=\"resource-trigger\" data-resource=\"engajar-fornecedores-para-reduzir-as-emissoes\" title=\"Engajar fornecedores para reduzir as emiss\u00f5es\"><\/span>\n                                                <\/div>\n\n                                            <\/div>\n\n\n\n                                                                                    <div class=\"block resource swiper-slide external\">\n                                                <div class=\"inner\">\n                                                    <div class=\"image\">\n                                                        <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/designasupply-1.jpg\">\n                                                                                                                                                                    <\/div>\n                                                    <div class=\"text\">\n                                                        <div class=\"label\">Recurso externo<\/div>                                                        <h3 class=\"title\">Desenhe um programa de engajamento de fornecedores<\/h3>\n                                                        <p><p>Desenvolva planos para trabalhar com fornecedores na redu\u00e7\u00e3o das emiss\u00f5es de carbono em sua cadeia de suprimentos.<\/p>\n<\/p>\n                                                    <\/div>\n\n                                                    <span class=\"resource-trigger\" data-resource=\"desenhe-um-programa-de-engajamento-de-fornecedores\" title=\"Desenhe um programa de engajamento de fornecedores\"><\/span>\n                                                <\/div>\n\n                                            <\/div>\n\n\n\n                                                                                    <div class=\"block resource swiper-slide course\">\n                                                <div class=\"inner\">\n                                                    <div class=\"image\">\n                                                        <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/climatefit-3.jpg\">\n                                                                                                                                                                    <\/div>\n                                                    <div class=\"text\">\n                                                        <div class=\"label\">Curso<\/div>                                                        <h3 class=\"title\">Reduza as emiss\u00f5es em sua cadeia de suprimentos.<\/h3>\n                                                        <p><p>Interagir com os fornecedores para abordar a quest\u00e3o das emiss\u00f5es na cadeia de suprimentos.<\/p>\n<\/p>\n                                                    <\/div>\n\n                                                    <span class=\"resource-trigger\" data-resource=\"reduza-as-emissoes-em-sua-cadeia-de-suprimentos\" title=\"Reduza as emiss\u00f5es em sua cadeia de suprimentos.\"><\/span>\n                                                <\/div>\n\n                                            <\/div>\n\n\n\n                                                                    <\/div>\n                        <\/div>\n                        <div style=\"display:flex;justify-content: center;margin-top: 20px;\">\n                            <div class=\"btn-slider slider-prev-0\">\n                                <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/backIco.svg\">\n\n                            <\/div>\n                            <div class=\"btn-slider slider-next-0\">\n                                <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/nextIco.svg\">\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                    <div class=\"bottom-border\"><\/div>                                                                    <div class=\"resource-modal\" tabindex=\"-1\" id=\"resource-engajar-fornecedores-para-reduzir-as-emissoes\" data-scrollable=\"true\">\n                                <div class=\"modal-container\">\n                                    <div class=\"close\">\n                                        <button class=\"hide-button\" data-target=\"close_resource\" type=\"button\">\n                                            <svg width=\"24\" height=\"24\" viewBox=\"0 0 684 684\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                                <path d=\"M640.66 0.659851C652.88 0.659851 663.044 4.7149 671.155 12.825C679.265 20.9351 683.32 31.1 683.32 43.3197C683.32 55.321 679.21 65.4313 670.991 73.6506L402.314 341.98L670.991 610.308C679.21 618.528 683.32 628.638 683.32 640.639C683.32 652.859 679.265 663.024 671.155 671.134C663.044 679.244 652.88 683.299 640.66 683.299C628.659 683.299 618.548 679.19 610.329 670.97L342 402.293L73.671 670.97C65.4517 679.19 55.3414 683.299 43.3401 683.299C31.1204 683.299 20.9555 679.244 12.8454 671.134C4.73535 663.024 0.680298 652.859 0.680298 640.639C0.680298 628.638 4.78996 618.528 13.0093 610.308L281.686 341.98L13.0093 73.6506C4.78996 65.4313 0.680298 55.321 0.680298 43.3197C0.680298 31.1 4.73535 20.9351 12.8454 12.825C20.9555 4.7149 31.1204 0.659851 43.3401 0.659851C55.3414 0.659851 65.4517 4.76951 73.671 12.9888L342 281.666L610.329 12.9888C618.548 4.76951 628.659 0.659851 640.66 0.659851Z\" fill=\"#125B60\"><\/path>\n                                            <\/svg>\n                                        <\/button>\n                                    <\/div>\n                                    <div class=\"resource-wrapper\">\n                                        <div class=\"media-wrapper\">\n                                                                                            <div class=\"media\">\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/workWithSuppliers-1-scaled-1.jpg\">\n                                                                                                    <\/div>\n\n                                                                                    <\/div>\n                                        <div class=\"content\">\n                                                                                            <h6>Guia de A\u00e7\u00e3o<\/h6>\n                                                                                        <h3>Engajar fornecedores para reduzir as emiss\u00f5es<\/h3>\n\n                                            <div class=\"description\">\n                                                <p>Este guia oferece uma abordagem passo a passo para colaborar com seus fornecedores na redu\u00e7\u00e3o das emiss\u00f5es em sua cadeia de valor. Ele fornece uma estrutura que incentiva os fornecedores a tomarem medidas contra as mudan\u00e7as clim\u00e1ticas. Siga os passos em ordem ou comece com as a\u00e7\u00f5es mais f\u00e1ceis de implementar a curto prazo.  <\/p>\n<p>Nossos Guias Pr\u00e1ticos priorizam a simplicidade e a rapidez, sendo adequados para todas as PMEs.<\/p>\n                                            <\/div>\n                                                                                            <div class=\"time\">\n                                                    <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/time.svg\">\n                                                    <p>Tempo estimado de conclus\u00e3o: 10 minutos<\/p>\n                                                <\/div>\n                                                                                                                                                                                    <div class=\"access\">\n                                                    <a href=\"https:\/\/smeclimatehub.org\/guides\/engaging-suppliers-to-reduce-emissions\/\" class=\"button\" target=\"\" title=\"Engajar fornecedores para reduzir as emiss\u00f5es\">Acessar recurso<\/a>\n                                                <\/div>\n                                                                                        <div class=\"star-rating-container\" data-resource=\"engajar-fornecedores-para-reduzir-as-emissoes\">\n                                                                                                        <div class=\"overall\">De forma geral, como voc\u00ea avaliaria este recurso?<\/div>\n                                                        <div class=\"star-rating-wrapper\">\n                                                            <div class=\"star-rating\" data-rating=\"0\">\n                                                                <span class=\"star\" data-value=\"1\"><\/span>\n                                                                <span class=\"star\" data-value=\"2\"><\/span>\n                                                                <span class=\"star\" data-value=\"3\"><\/span>\n                                                                <span class=\"star\" data-value=\"4\"><\/span>\n                                                                <span class=\"star\" data-value=\"5\"><\/span>\n                                                            <\/div>\n                                                            <div class=\"star-labels\">\n                                                                <span class=\"star-label poor\">Pobre<\/span>\n                                                                <span class=\"star-label excellent\">Excelente<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                        <div class=\"thank-you-message\" style=\"display: none;\">Obrigado por avaliar este recurso!<\/div>\n                                                                                                    <div class=\"loading\">\n                                                    <span class=\"loader-new\"><\/span>\n                                                <\/div>\n                                            <\/div>\n\n\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                                                <div class=\"resource-modal\" tabindex=\"-1\" id=\"resource-desenhe-um-programa-de-engajamento-de-fornecedores\" data-scrollable=\"true\">\n                                <div class=\"modal-container\">\n                                    <div class=\"close\">\n                                        <button class=\"hide-button\" data-target=\"close_resource\" type=\"button\">\n                                            <svg width=\"24\" height=\"24\" viewBox=\"0 0 684 684\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                                <path d=\"M640.66 0.659851C652.88 0.659851 663.044 4.7149 671.155 12.825C679.265 20.9351 683.32 31.1 683.32 43.3197C683.32 55.321 679.21 65.4313 670.991 73.6506L402.314 341.98L670.991 610.308C679.21 618.528 683.32 628.638 683.32 640.639C683.32 652.859 679.265 663.024 671.155 671.134C663.044 679.244 652.88 683.299 640.66 683.299C628.659 683.299 618.548 679.19 610.329 670.97L342 402.293L73.671 670.97C65.4517 679.19 55.3414 683.299 43.3401 683.299C31.1204 683.299 20.9555 679.244 12.8454 671.134C4.73535 663.024 0.680298 652.859 0.680298 640.639C0.680298 628.638 4.78996 618.528 13.0093 610.308L281.686 341.98L13.0093 73.6506C4.78996 65.4313 0.680298 55.321 0.680298 43.3197C0.680298 31.1 4.73535 20.9351 12.8454 12.825C20.9555 4.7149 31.1204 0.659851 43.3401 0.659851C55.3414 0.659851 65.4517 4.76951 73.671 12.9888L342 281.666L610.329 12.9888C618.548 4.76951 628.659 0.659851 640.66 0.659851Z\" fill=\"#125B60\"><\/path>\n                                            <\/svg>\n                                        <\/button>\n                                    <\/div>\n                                    <div class=\"resource-wrapper\">\n                                        <div class=\"media-wrapper\">\n                                                                                            <div class=\"media\">\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/Design-a-supplier-engagement-programme.png\">\n                                                                                                    <\/div>\n\n                                                                                    <\/div>\n                                        <div class=\"content\">\n                                                                                            <h6>Recurso externo<\/h6>\n                                                                                        <h3>Desenhe um programa de engajamento de fornecedores<\/h3>\n\n                                            <div class=\"description\">\n                                                <p>As emiss\u00f5es de Escopo 3 contribuem substancialmente para a pegada de carbono de uma organiza\u00e7\u00e3o. Este recurso descreve como desenvolver planos de engajamento de fornecedores para a descarboniza\u00e7\u00e3o a montante do Escopo 3, garantindo sua ades\u00e3o, personalizando o engajamento e apoiando a jornada de descarboniza\u00e7\u00e3o dos fornecedores. <\/p>\n<p>Este recurso \u00e9 particularmente \u00fatil para PMEs de maior porte com um n\u00famero consider\u00e1vel de fornecedores.<\/p>\n                                            <\/div>\n                                                                                            <div class=\"time\">\n                                                    <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/time.svg\">\n                                                    <p>Tempo estimado de conclus\u00e3o: 10 minutos<\/p>\n                                                <\/div>\n                                                                                                                                        <div class=\"provider\">\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/Climate-Drive-Logo.jpg\">\n                                                                                                                                                                <p>Fornecido pelo WBCSD<\/p>\n                                                                                                    <\/div>\n                                                                                                                                        <div class=\"access\">\n                                                    <a href=\"https:\/\/www.theclimatedrive.org\/action-library\/designing-a-supplier-engagement-program\" class=\"button\" target=\"_blank\" title=\"Desenhe um programa de engajamento de fornecedores\">Acessar recurso<\/a>\n                                                <\/div>\n                                                                                        <div class=\"star-rating-container\" data-resource=\"desenhe-um-programa-de-engajamento-de-fornecedores\">\n                                                                                                <div class=\"loading\">\n                                                    <span class=\"loader-new\"><\/span>\n                                                <\/div>\n                                            <\/div>\n\n\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                                                <div class=\"resource-modal\" tabindex=\"-1\" id=\"resource-reduza-as-emissoes-em-sua-cadeia-de-suprimentos\" data-scrollable=\"true\">\n                                <div class=\"modal-container\">\n                                    <div class=\"close\">\n                                        <button class=\"hide-button\" data-target=\"close_resource\" type=\"button\">\n                                            <svg width=\"24\" height=\"24\" viewBox=\"0 0 684 684\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                                <path d=\"M640.66 0.659851C652.88 0.659851 663.044 4.7149 671.155 12.825C679.265 20.9351 683.32 31.1 683.32 43.3197C683.32 55.321 679.21 65.4313 670.991 73.6506L402.314 341.98L670.991 610.308C679.21 618.528 683.32 628.638 683.32 640.639C683.32 652.859 679.265 663.024 671.155 671.134C663.044 679.244 652.88 683.299 640.66 683.299C628.659 683.299 618.548 679.19 610.329 670.97L342 402.293L73.671 670.97C65.4517 679.19 55.3414 683.299 43.3401 683.299C31.1204 683.299 20.9555 679.244 12.8454 671.134C4.73535 663.024 0.680298 652.859 0.680298 640.639C0.680298 628.638 4.78996 618.528 13.0093 610.308L281.686 341.98L13.0093 73.6506C4.78996 65.4313 0.680298 55.321 0.680298 43.3197C0.680298 31.1 4.73535 20.9351 12.8454 12.825C20.9555 4.7149 31.1204 0.659851 43.3401 0.659851C55.3414 0.659851 65.4517 4.76951 73.671 12.9888L342 281.666L610.329 12.9888C618.548 4.76951 628.659 0.659851 640.66 0.659851Z\" fill=\"#125B60\"><\/path>\n                                            <\/svg>\n                                        <\/button>\n                                    <\/div>\n                                    <div class=\"resource-wrapper\">\n                                        <div class=\"media-wrapper\">\n                                                                                            <div class=\"media\">\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/climatefit-3.jpg\">\n                                                                                                    <\/div>\n\n                                                                                    <\/div>\n                                        <div class=\"content\">\n                                                                                            <h6>Curso<\/h6>\n                                                                                        <h3>Reduza as emiss\u00f5es em sua cadeia de suprimentos.<\/h3>\n\n                                            <div class=\"description\">\n                                                <p>As emiss\u00f5es de Escopo 3 compreendem aquelas resultantes das atividades da sua empresa, mas que n\u00e3o est\u00e3o sob o seu controle direto. Este m\u00f3dulo ir\u00e1 orient\u00e1-lo sobre o que voc\u00ea pode fazer para mudar o funcionamento da sua cadeia de suprimentos, bem como sobre como trabalhar com seus fornecedores para incentiv\u00e1-los a reduzir suas pr\u00f3prias emiss\u00f5es. <\/p>\n<p>Nossos cursos s\u00e3o projetados para PMEs de todos os portes e representam um \u00f3timo ponto de partida para quem est\u00e1 come\u00e7ando.<\/p>\n                                            <\/div>\n                                                                                            <div class=\"time\">\n                                                    <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/time.svg\">\n                                                    <p>Tempo estimado de conclus\u00e3o: 30 minutos<\/p>\n                                                <\/div>\n                                                                                                                                        <div class=\"provider\">\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/BSR-AND-CISL.png\">\n                                                                                                                                                        <\/div>\n                                                                                                                                        <div class=\"access\">\n                                                    <a href=\"https:\/\/smeclimatehub.org\/wp-json\/lw\/v1\/sso?redirectUrl=https%3A%2F%2Facademy.smeclimatehub.org%2Fcourse%2Freducing-emissions-in-your-supply-chain\" class=\"button\" target=\"_blank\" title=\"Reduza as emiss\u00f5es em sua cadeia de suprimentos.\">Acessar recurso<\/a>\n                                                <\/div>\n                                                                                        <div class=\"star-rating-container\" data-resource=\"reduza-as-emissoes-em-sua-cadeia-de-suprimentos\">\n                                                                                                <div class=\"loading\">\n                                                    <span class=\"loader-new\"><\/span>\n                                                <\/div>\n                                            <\/div>\n\n\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                    \n                <\/div>\n\n\n            <\/div>\n        <\/section>\n            <section class=\"action-space-blocks align-content-top light light content-block\">\n            <div class=\"container\">\n                <div class=\"area-blocks\">\n                    <div class=\"area-block\">\n                                                <div class=\"stage\"><div class=\"number\">02<\/div><div class=\"title\">Maduro<\/div><div class=\"stage-info\"> <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/matureIcon.svg\"> Estabelecer metas<\/div><\/div>                                                                        <div class=\"outer-blocks swiper\">\n                            <div class=\"blocks-wrapper swiper-wrapper\">\n                                                                            <div class=\"block resource swiper-slide guide\">\n                                                <div class=\"inner\">\n                                                    <div class=\"image\">\n                                                        <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/dataEquipments-1-scaled-1.jpg\">\n                                                                                                                                                                    <\/div>\n                                                    <div class=\"text\">\n                                                        <div class=\"label\">Guia de A\u00e7\u00e3o<\/div>                                                        <h3 class=\"title\">Reduzir as emiss\u00f5es provenientes de servi\u00e7os de dados e TI.<\/h3>\n                                                        <p><p>Siga estes passos para reduzir as emiss\u00f5es de gases de efeito estufa provenientes de equipamentos de TI e de dados.<\/p>\n<\/p>\n                                                    <\/div>\n\n                                                    <span class=\"resource-trigger\" data-resource=\"reduzir-as-emissoes-provenientes-de-servicos-de-dados-e-ti\" title=\"Reduzir as emiss\u00f5es provenientes de servi\u00e7os de dados e TI.\"><\/span>\n                                                <\/div>\n\n                                            <\/div>\n\n\n\n                                                                                    <div class=\"block resource swiper-slide guide\">\n                                                <div class=\"inner\">\n                                                    <div class=\"image\">\n                                                        <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/shippingTransportation-1-scaled-1.jpg\">\n                                                                                                                                                                    <\/div>\n                                                    <div class=\"text\">\n                                                        <div class=\"label\">Guia de A\u00e7\u00e3o<\/div>                                                        <h3 class=\"title\">Reduzir as emiss\u00f5es do transporte de mercadorias e cargas.<\/h3>\n                                                        <p><p>Aborde as emiss\u00f5es provenientes do seu transporte mar\u00edtimo e de mercadorias.<\/p>\n<\/p>\n                                                    <\/div>\n\n                                                    <span class=\"resource-trigger\" data-resource=\"reduzir-as-emissoes-do-transporte-de-mercadorias-e-cargas\" title=\"Reduzir as emiss\u00f5es do transporte de mercadorias e cargas.\"><\/span>\n                                                <\/div>\n\n                                            <\/div>\n\n\n\n                                                                    <\/div>\n                        <\/div>\n                        <div style=\"display:flex;justify-content: center;margin-top: 20px;\">\n                            <div class=\"btn-slider slider-prev-1\">\n                                <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/backIco.svg\">\n\n                            <\/div>\n                            <div class=\"btn-slider slider-next-1\">\n                                <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/nextIco.svg\">\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                    <div class=\"bottom-border\"><\/div>                                                                    <div class=\"resource-modal\" tabindex=\"-1\" id=\"resource-reduzir-as-emissoes-provenientes-de-servicos-de-dados-e-ti\" data-scrollable=\"true\">\n                                <div class=\"modal-container\">\n                                    <div class=\"close\">\n                                        <button class=\"hide-button\" data-target=\"close_resource\" type=\"button\">\n                                            <svg width=\"24\" height=\"24\" viewBox=\"0 0 684 684\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                                <path d=\"M640.66 0.659851C652.88 0.659851 663.044 4.7149 671.155 12.825C679.265 20.9351 683.32 31.1 683.32 43.3197C683.32 55.321 679.21 65.4313 670.991 73.6506L402.314 341.98L670.991 610.308C679.21 618.528 683.32 628.638 683.32 640.639C683.32 652.859 679.265 663.024 671.155 671.134C663.044 679.244 652.88 683.299 640.66 683.299C628.659 683.299 618.548 679.19 610.329 670.97L342 402.293L73.671 670.97C65.4517 679.19 55.3414 683.299 43.3401 683.299C31.1204 683.299 20.9555 679.244 12.8454 671.134C4.73535 663.024 0.680298 652.859 0.680298 640.639C0.680298 628.638 4.78996 618.528 13.0093 610.308L281.686 341.98L13.0093 73.6506C4.78996 65.4313 0.680298 55.321 0.680298 43.3197C0.680298 31.1 4.73535 20.9351 12.8454 12.825C20.9555 4.7149 31.1204 0.659851 43.3401 0.659851C55.3414 0.659851 65.4517 4.76951 73.671 12.9888L342 281.666L610.329 12.9888C618.548 4.76951 628.659 0.659851 640.66 0.659851Z\" fill=\"#125B60\"><\/path>\n                                            <\/svg>\n                                        <\/button>\n                                    <\/div>\n                                    <div class=\"resource-wrapper\">\n                                        <div class=\"media-wrapper\">\n                                                                                            <div class=\"media\">\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/dataEquipments-1-scaled-1.jpg\">\n                                                                                                    <\/div>\n\n                                                                                    <\/div>\n                                        <div class=\"content\">\n                                                                                            <h6>Guia de A\u00e7\u00e3o<\/h6>\n                                                                                        <h3>Reduzir as emiss\u00f5es provenientes de servi\u00e7os de dados e TI.<\/h3>\n\n                                            <div class=\"description\">\n                                                <p>Este guia orienta voc\u00ea passo a passo na redu\u00e7\u00e3o das emiss\u00f5es de gases de efeito estufa provenientes de seus equipamentos de TI e dados, incluindo dispositivos como telefones, computadores, servidores e impressoras, comuns em escrit\u00f3rios.<\/p>\n<p> Nossos Guias Pr\u00e1ticos priorizam a simplicidade e a rapidez, sendo adequados para todas as PMEs.<\/p>\n                                            <\/div>\n                                                                                            <div class=\"time\">\n                                                    <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/time.svg\">\n                                                    <p>Tempo estimado de conclus\u00e3o: 10 minutos<\/p>\n                                                <\/div>\n                                                                                                                                                                                    <div class=\"access\">\n                                                    <a href=\"https:\/\/smeclimatehub.org\/guides\/reducing-emissions-from-data-and-it-equipment-services\/\" class=\"button\" target=\"\" title=\"Reduzir as emiss\u00f5es provenientes de servi\u00e7os de dados e TI.\">Acessar recurso<\/a>\n                                                <\/div>\n                                                                                        <div class=\"star-rating-container\" data-resource=\"reduzir-as-emissoes-provenientes-de-servicos-de-dados-e-ti\">\n                                                                                                        <div class=\"overall\">De forma geral, como voc\u00ea avaliaria este recurso?<\/div>\n                                                        <div class=\"star-rating-wrapper\">\n                                                            <div class=\"star-rating\" data-rating=\"0\">\n                                                                <span class=\"star\" data-value=\"1\"><\/span>\n                                                                <span class=\"star\" data-value=\"2\"><\/span>\n                                                                <span class=\"star\" data-value=\"3\"><\/span>\n                                                                <span class=\"star\" data-value=\"4\"><\/span>\n                                                                <span class=\"star\" data-value=\"5\"><\/span>\n                                                            <\/div>\n                                                            <div class=\"star-labels\">\n                                                                <span class=\"star-label poor\">Pobre<\/span>\n                                                                <span class=\"star-label excellent\">Excelente<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                        <div class=\"thank-you-message\" style=\"display: none;\">Obrigado por avaliar este recurso!<\/div>\n                                                                                                    <div class=\"loading\">\n                                                    <span class=\"loader-new\"><\/span>\n                                                <\/div>\n                                            <\/div>\n\n\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                                                <div class=\"resource-modal\" tabindex=\"-1\" id=\"resource-reduzir-as-emissoes-do-transporte-de-mercadorias-e-cargas\" data-scrollable=\"true\">\n                                <div class=\"modal-container\">\n                                    <div class=\"close\">\n                                        <button class=\"hide-button\" data-target=\"close_resource\" type=\"button\">\n                                            <svg width=\"24\" height=\"24\" viewBox=\"0 0 684 684\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                                <path d=\"M640.66 0.659851C652.88 0.659851 663.044 4.7149 671.155 12.825C679.265 20.9351 683.32 31.1 683.32 43.3197C683.32 55.321 679.21 65.4313 670.991 73.6506L402.314 341.98L670.991 610.308C679.21 618.528 683.32 628.638 683.32 640.639C683.32 652.859 679.265 663.024 671.155 671.134C663.044 679.244 652.88 683.299 640.66 683.299C628.659 683.299 618.548 679.19 610.329 670.97L342 402.293L73.671 670.97C65.4517 679.19 55.3414 683.299 43.3401 683.299C31.1204 683.299 20.9555 679.244 12.8454 671.134C4.73535 663.024 0.680298 652.859 0.680298 640.639C0.680298 628.638 4.78996 618.528 13.0093 610.308L281.686 341.98L13.0093 73.6506C4.78996 65.4313 0.680298 55.321 0.680298 43.3197C0.680298 31.1 4.73535 20.9351 12.8454 12.825C20.9555 4.7149 31.1204 0.659851 43.3401 0.659851C55.3414 0.659851 65.4517 4.76951 73.671 12.9888L342 281.666L610.329 12.9888C618.548 4.76951 628.659 0.659851 640.66 0.659851Z\" fill=\"#125B60\"><\/path>\n                                            <\/svg>\n                                        <\/button>\n                                    <\/div>\n                                    <div class=\"resource-wrapper\">\n                                        <div class=\"media-wrapper\">\n                                                                                            <div class=\"media\">\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/shippingTransportation-1-scaled-1.jpg\">\n                                                                                                    <\/div>\n\n                                                                                    <\/div>\n                                        <div class=\"content\">\n                                                                                            <h6>Guia de A\u00e7\u00e3o<\/h6>\n                                                                                        <h3>Reduzir as emiss\u00f5es do transporte de mercadorias e cargas.<\/h3>\n\n                                            <div class=\"description\">\n                                                <p>O setor de transporte mar\u00edtimo \u00e9 respons\u00e1vel por oito por cento das emiss\u00f5es globais de carbono. J\u00e1 existem solu\u00e7\u00f5es que as empresas podem implementar para reduzir drasticamente essas emiss\u00f5es. Este guia aborda como reduzir as emiss\u00f5es do transporte mar\u00edtimo e de mercadorias.  <\/p>\n<p>Nossos Guias Pr\u00e1ticos priorizam a simplicidade e a rapidez, sendo adequados para todas as PMEs.<\/p>\n                                            <\/div>\n                                                                                            <div class=\"time\">\n                                                    <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/time.svg\">\n                                                    <p>Tempo estimado de conclus\u00e3o: 10 minutos<\/p>\n                                                <\/div>\n                                                                                                                                                                                    <div class=\"access\">\n                                                    <a href=\"https:\/\/smeclimatehub.org\/guides\/reduce-emissions-from-freight-and-goods-transport\/\" class=\"button\" target=\"\" title=\"Reduzir as emiss\u00f5es do transporte de mercadorias e cargas.\">Acessar recurso<\/a>\n                                                <\/div>\n                                                                                        <div class=\"star-rating-container\" data-resource=\"reduzir-as-emissoes-do-transporte-de-mercadorias-e-cargas\">\n                                                                                                        <div class=\"overall\">De forma geral, como voc\u00ea avaliaria este recurso?<\/div>\n                                                        <div class=\"star-rating-wrapper\">\n                                                            <div class=\"star-rating\" data-rating=\"0\">\n                                                                <span class=\"star\" data-value=\"1\"><\/span>\n                                                                <span class=\"star\" data-value=\"2\"><\/span>\n                                                                <span class=\"star\" data-value=\"3\"><\/span>\n                                                                <span class=\"star\" data-value=\"4\"><\/span>\n                                                                <span class=\"star\" data-value=\"5\"><\/span>\n                                                            <\/div>\n                                                            <div class=\"star-labels\">\n                                                                <span class=\"star-label poor\">Pobre<\/span>\n                                                                <span class=\"star-label excellent\">Excelente<\/span>\n                                                            <\/div>\n                                                        <\/div>\n                                                        <div class=\"thank-you-message\" style=\"display: none;\">Obrigado por avaliar este recurso!<\/div>\n                                                                                                    <div class=\"loading\">\n                                                    <span class=\"loader-new\"><\/span>\n                                                <\/div>\n                                            <\/div>\n\n\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                    \n                <\/div>\n\n\n            <\/div>\n        <\/section>\n            <section class=\"action-space-blocks align-content-top light light light content-block\">\n            <div class=\"container\">\n                <div class=\"area-blocks\">\n                    <div class=\"area-block\">\n                                                <div class=\"stage\"><div class=\"number\">03<\/div><div class=\"title\">Liderar<\/div><div class=\"stage-info\"> <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/leadIcon.svg\"> Acelere o progresso<\/div><\/div>                                                                        <div class=\"outer-blocks swiper\">\n                            <div class=\"blocks-wrapper swiper-wrapper\">\n                                                                            <div class=\"block resource swiper-slide course\">\n                                                <div class=\"inner\">\n                                                    <div class=\"image\">\n                                                        <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/climatefit-4.jpg\">\n                                                                                                                                                                    <\/div>\n                                                    <div class=\"text\">\n                                                        <div class=\"label\">Curso<\/div>                                                        <h3 class=\"title\">Design para emiss\u00f5es l\u00edquidas zero<\/h3>\n                                                        <p><p>Um conjunto de ferramentas para o design de produtos sustent\u00e1veis.<\/p>\n<\/p>\n                                                    <\/div>\n\n                                                    <span class=\"resource-trigger\" data-resource=\"design-para-emissoes-liquidas-zero\" title=\"Design para emiss\u00f5es l\u00edquidas zero\"><\/span>\n                                                <\/div>\n\n                                            <\/div>\n\n\n\n                                                                                    <div class=\"block resource swiper-slide external\">\n                                                <div class=\"inner\">\n                                                    <div class=\"image\">\n                                                        <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/pexels-fauxels-3184436-1.jpg\">\n                                                                                                                                                                    <\/div>\n                                                    <div class=\"text\">\n                                                        <div class=\"label\">Recurso externo<\/div>                                                        <h3 class=\"title\">Utilize alian\u00e7as e coinvestimentos.<\/h3>\n                                                        <p><p>Construir e utilizar parcerias para solucionar os desafios da descarboniza\u00e7\u00e3o.<\/p>\n<\/p>\n                                                    <\/div>\n\n                                                    <span class=\"resource-trigger\" data-resource=\"utilize-aliancas-e-coinvestimentos\" title=\"Utilize alian\u00e7as e coinvestimentos.\"><\/span>\n                                                <\/div>\n\n                                            <\/div>\n\n\n\n                                                                    <\/div>\n                        <\/div>\n                        <div style=\"display:flex;justify-content: center;margin-top: 20px;\">\n                            <div class=\"btn-slider slider-prev-2\">\n                                <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/backIco.svg\">\n\n                            <\/div>\n                            <div class=\"btn-slider slider-next-2\">\n                                <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/nextIco.svg\">\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                                                                                        <div class=\"resource-modal\" tabindex=\"-1\" id=\"resource-design-para-emissoes-liquidas-zero\" data-scrollable=\"true\">\n                                <div class=\"modal-container\">\n                                    <div class=\"close\">\n                                        <button class=\"hide-button\" data-target=\"close_resource\" type=\"button\">\n                                            <svg width=\"24\" height=\"24\" viewBox=\"0 0 684 684\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                                <path d=\"M640.66 0.659851C652.88 0.659851 663.044 4.7149 671.155 12.825C679.265 20.9351 683.32 31.1 683.32 43.3197C683.32 55.321 679.21 65.4313 670.991 73.6506L402.314 341.98L670.991 610.308C679.21 618.528 683.32 628.638 683.32 640.639C683.32 652.859 679.265 663.024 671.155 671.134C663.044 679.244 652.88 683.299 640.66 683.299C628.659 683.299 618.548 679.19 610.329 670.97L342 402.293L73.671 670.97C65.4517 679.19 55.3414 683.299 43.3401 683.299C31.1204 683.299 20.9555 679.244 12.8454 671.134C4.73535 663.024 0.680298 652.859 0.680298 640.639C0.680298 628.638 4.78996 618.528 13.0093 610.308L281.686 341.98L13.0093 73.6506C4.78996 65.4313 0.680298 55.321 0.680298 43.3197C0.680298 31.1 4.73535 20.9351 12.8454 12.825C20.9555 4.7149 31.1204 0.659851 43.3401 0.659851C55.3414 0.659851 65.4517 4.76951 73.671 12.9888L342 281.666L610.329 12.9888C618.548 4.76951 628.659 0.659851 640.66 0.659851Z\" fill=\"#125B60\"><\/path>\n                                            <\/svg>\n                                        <\/button>\n                                    <\/div>\n                                    <div class=\"resource-wrapper\">\n                                        <div class=\"media-wrapper\">\n                                                                                            <div class=\"media\">\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/climatefit-4.jpg\">\n                                                                                                    <\/div>\n\n                                                                                    <\/div>\n                                        <div class=\"content\">\n                                                                                            <h6>Curso<\/h6>\n                                                                                        <h3>Design para emiss\u00f5es l\u00edquidas zero<\/h3>\n\n                                            <div class=\"description\">\n                                                <p>Um guia b\u00e1sico e simples para profissionais sem forma\u00e7\u00e3o em design aprenderem sobre o papel do design na redu\u00e7\u00e3o de emiss\u00f5es e as melhores pr\u00e1ticas para implementar mudan\u00e7as. Este m\u00f3dulo ajudar\u00e1 voc\u00ea a considerar diferentes aspectos do design de produtos mais sustent\u00e1veis. <\/p>\n<p>Nossos cursos s\u00e3o projetados para PMEs de todos os portes e servem como um bom ponto de partida para quem est\u00e1 come\u00e7ando.<\/p>\n                                            <\/div>\n                                                                                            <div class=\"time\">\n                                                    <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/time.svg\">\n                                                    <p>Tempo estimado de conclus\u00e3o: 30 minutos<\/p>\n                                                <\/div>\n                                                                                                                                        <div class=\"provider\">\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/BSR-AND-CISL.png\">\n                                                                                                                                                        <\/div>\n                                                                                                                                        <div class=\"access\">\n                                                    <a href=\"https:\/\/smeclimatehub.org\/wp-json\/lw\/v1\/sso?redirectUrl=https%3A%2F%2Facademy.smeclimatehub.org%2Fcourse%2Fdesign-for-net-zero\" class=\"button\" target=\"_blank\" title=\"Design para emiss\u00f5es l\u00edquidas zero\">Acessar recurso<\/a>\n                                                <\/div>\n                                                                                        <div class=\"star-rating-container\" data-resource=\"design-para-emissoes-liquidas-zero\">\n                                                                                                <div class=\"loading\">\n                                                    <span class=\"loader-new\"><\/span>\n                                                <\/div>\n                                            <\/div>\n\n\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                                                <div class=\"resource-modal\" tabindex=\"-1\" id=\"resource-utilize-aliancas-e-coinvestimentos\" data-scrollable=\"true\">\n                                <div class=\"modal-container\">\n                                    <div class=\"close\">\n                                        <button class=\"hide-button\" data-target=\"close_resource\" type=\"button\">\n                                            <svg width=\"24\" height=\"24\" viewBox=\"0 0 684 684\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                                <path d=\"M640.66 0.659851C652.88 0.659851 663.044 4.7149 671.155 12.825C679.265 20.9351 683.32 31.1 683.32 43.3197C683.32 55.321 679.21 65.4313 670.991 73.6506L402.314 341.98L670.991 610.308C679.21 618.528 683.32 628.638 683.32 640.639C683.32 652.859 679.265 663.024 671.155 671.134C663.044 679.244 652.88 683.299 640.66 683.299C628.659 683.299 618.548 679.19 610.329 670.97L342 402.293L73.671 670.97C65.4517 679.19 55.3414 683.299 43.3401 683.299C31.1204 683.299 20.9555 679.244 12.8454 671.134C4.73535 663.024 0.680298 652.859 0.680298 640.639C0.680298 628.638 4.78996 618.528 13.0093 610.308L281.686 341.98L13.0093 73.6506C4.78996 65.4313 0.680298 55.321 0.680298 43.3197C0.680298 31.1 4.73535 20.9351 12.8454 12.825C20.9555 4.7149 31.1204 0.659851 43.3401 0.659851C55.3414 0.659851 65.4517 4.76951 73.671 12.9888L342 281.666L610.329 12.9888C618.548 4.76951 628.659 0.659851 640.66 0.659851Z\" fill=\"#125B60\"><\/path>\n                                            <\/svg>\n                                        <\/button>\n                                    <\/div>\n                                    <div class=\"resource-wrapper\">\n                                        <div class=\"media-wrapper\">\n                                                                                            <div class=\"media\">\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/pexels-fauxels-3184436-1.jpg\">\n                                                                                                    <\/div>\n\n                                                                                    <\/div>\n                                        <div class=\"content\">\n                                                                                            <h6>Recurso externo<\/h6>\n                                                                                        <h3>Utilize alian\u00e7as e coinvestimentos.<\/h3>\n\n                                            <div class=\"description\">\n                                                <p>As empresas enfrentam muitos desafios na descarboniza\u00e7\u00e3o de suas cadeias de suprimentos que n\u00e3o podem ser superados individualmente. As parcerias podem ajudar a resolver esses desafios de descarboniza\u00e7\u00e3o e permitir que as PMEs aproveitem as a\u00e7\u00f5es das empresas com as quais trabalham. Este recurso descreve como identificar e construir parcerias relevantes.  <\/p>\n                                            <\/div>\n                                                                                            <div class=\"time\">\n                                                    <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/time.svg\">\n                                                    <p>Tempo estimado de conclus\u00e3o: 15 minutos<\/p>\n                                                <\/div>\n                                                                                                                                        <div class=\"provider\">\n                                                                                                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/10\/Climate-Drive-Logo.jpg\">\n                                                                                                                                                                <p>Fornecido pelo WBCSD<\/p>\n                                                                                                    <\/div>\n                                                                                                                                        <div class=\"access\">\n                                                    <a href=\"https:\/\/www.theclimatedrive.org\/action-library\/building-partnerships-through-alliances-and-co-investments\" class=\"button\" target=\"_blank\" title=\"Utilize alian\u00e7as e coinvestimentos.\">Acessar recurso<\/a>\n                                                <\/div>\n                                                                                        <div class=\"star-rating-container\" data-resource=\"utilize-aliancas-e-coinvestimentos\">\n                                                                                                <div class=\"loading\">\n                                                    <span class=\"loader-new\"><\/span>\n                                                <\/div>\n                                            <\/div>\n\n\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                    \n                <\/div>\n\n\n            <\/div>\n        <\/section>\n    \n\n\n<section id=\"block-6865626b7dc0a\"  class=\"case-studies-section pt-full-new pb-full-new\">\n\t<div class=\"container\">\n\t\t<div class=\"content-block\">\n<div class=\"block-header\">\n\t\t\t\t\t\t\t\t<h2 class=\"title-section\">\n\t\t\t\t\tEstudos de caso\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-wrap\">\n\t\t\t\t<a href=\"\/news\" class=\"button\" target=\"_self\">Ver mais<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"outer-wrapper swiper\" dir=\"\">\n\t\t\t\t\t<div class=\"blocks-wrapper swiper-wrapper\">\n\t\t\t\t\t\t\t      <div class=\"block swiper-slide\">\n                                                <div class=\"inner\">\n                                                             <div class=\"image\">\n                                                        <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/09\/Miir2.jpeg\">\n\n                                                    <\/div>\n                                                <div class=\"text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"post-info\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsetembro 21, 2022\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"category\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tArticle\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                                                                                                                     <h3 class=\"title\">Responsible Sustainable Drinkware Company MiiR Proves Small Climate-Action Steps Yield Big Rewards\u00a0\u00a0<\/h3>\n                                                        <p>For companies on the fence about climate-action initiatives, responsible steel drinkware brand MiiR&#8230;<\/p>\n                                                    <\/div>\n                                              \n                                                 <a aria-label=\"Responsible Sustainable Drinkware Company MiiR Proves Small Climate-Action Steps Yield Big Rewards\u00a0\u00a0\" title=\"Responsible Sustainable Drinkware Company MiiR Proves Small Climate-Action Steps Yield Big Rewards\u00a0\u00a0\" href=\"https:\/\/smeclimatehub.org\/pt-br\/responsible-sustainable-drinkware-company-miir-proves-small-climate-action-steps-yield-big-rewards\/\" class=\"link\"><\/a>\n                                                <\/div>\n\n                                            <\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"navigation-buttons\">\n                            <div class=\"nav-button case-prev\">\n                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/arrow-left2.svg\">\n\n                            <\/div>\n                            <div class=\"nav-button case-next\">\n                            <img decoding=\"async\" src=\"https:\/\/smeclimatehub.org\/wp-content\/themes\/newsme\/assets\/images\/arrow-right2.svg\">\n                            <\/div>\n                        <\/div>\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n<section class=\"pb-full\" style=\"background: #FDFDFD;\">\n\n<\/section>\n\n\n<div class=\"stay-updated-block darkBackground \">\n\t<div class=\"container\">\n<div class=\"column\">\n<h2>Mantenha-se atualizado<\/h2>\n<p>Inscreva-se em nossa newsletter para se manter atualizado com as \u00faltimas novidades sobre o clima.<\/p>\n<\/div>\n<div class=\"column\">\n\t<button data-popup-button=\"stay-updated-form\" type=\"button\" class=\"button none\">Inscreva-se<\/button>\n<\/div>\n<\/div>\n\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":18450,"featured_media":0,"parent":93008,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-action-area.php","meta":{"_acf_changed":true,"inline_featured_image":false,"footnotes":""},"class_list":["post-93083","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<title>Cadeias de abastecimento - SME Climate Hub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smeclimatehub.org\/pt-br\/espaco-de-acao\/cadeias-de-abastecimento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cadeias de abastecimento - SME Climate Hub\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smeclimatehub.org\/pt-br\/espaco-de-acao\/cadeias-de-abastecimento\/\" \/>\n<meta property=\"og:site_name\" content=\"SME Climate Hub\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-04T20:24:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/08\/Preview_four.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1124\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smeclimatehub.org\\\/pt-br\\\/espaco-de-acao\\\/cadeias-de-abastecimento\\\/\",\"url\":\"https:\\\/\\\/smeclimatehub.org\\\/pt-br\\\/espaco-de-acao\\\/cadeias-de-abastecimento\\\/\",\"name\":\"Cadeias de abastecimento - SME Climate Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/businessclimatehub.org\\\/es\\\/#website\"},\"datePublished\":\"2024-10-07T15:06:37+00:00\",\"dateModified\":\"2025-11-04T20:24:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smeclimatehub.org\\\/pt-br\\\/espaco-de-acao\\\/cadeias-de-abastecimento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smeclimatehub.org\\\/pt-br\\\/espaco-de-acao\\\/cadeias-de-abastecimento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smeclimatehub.org\\\/pt-br\\\/espaco-de-acao\\\/cadeias-de-abastecimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smeclimatehub.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espa\u00e7o de a\u00e7\u00e3o\",\"item\":\"https:\\\/\\\/smeclimatehub.org\\\/pt-br\\\/espaco-de-acao\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cadeias de abastecimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/businessclimatehub.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/businessclimatehub.org\\\/es\\\/\",\"name\":\"SME Climate hub\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/businessclimatehub.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/businessclimatehub.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/businessclimatehub.org\\\/es\\\/#organization\",\"name\":\"SME Climate hub\",\"url\":\"https:\\\/\\\/businessclimatehub.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/businessclimatehub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smeclimatehub.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/57478-SME-Climate-Hub-logo-teal_1-cropped.svg\",\"contentUrl\":\"https:\\\/\\\/smeclimatehub.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/57478-SME-Climate-Hub-logo-teal_1-cropped.svg\",\"caption\":\"SME Climate hub\"},\"image\":{\"@id\":\"https:\\\/\\\/businessclimatehub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"Cadeias de abastecimento - SME Climate Hub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smeclimatehub.org\/pt-br\/espaco-de-acao\/cadeias-de-abastecimento\/","og_locale":"pt_BR","og_type":"article","og_title":"Cadeias de abastecimento - SME Climate Hub","og_url":"https:\/\/smeclimatehub.org\/pt-br\/espaco-de-acao\/cadeias-de-abastecimento\/","og_site_name":"SME Climate Hub","article_modified_time":"2025-11-04T20:24:58+00:00","og_image":[{"width":2000,"height":1124,"url":"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2024\/08\/Preview_four.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smeclimatehub.org\/pt-br\/espaco-de-acao\/cadeias-de-abastecimento\/","url":"https:\/\/smeclimatehub.org\/pt-br\/espaco-de-acao\/cadeias-de-abastecimento\/","name":"Cadeias de abastecimento - SME Climate Hub","isPartOf":{"@id":"https:\/\/businessclimatehub.org\/es\/#website"},"datePublished":"2024-10-07T15:06:37+00:00","dateModified":"2025-11-04T20:24:58+00:00","breadcrumb":{"@id":"https:\/\/smeclimatehub.org\/pt-br\/espaco-de-acao\/cadeias-de-abastecimento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smeclimatehub.org\/pt-br\/espaco-de-acao\/cadeias-de-abastecimento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/smeclimatehub.org\/pt-br\/espaco-de-acao\/cadeias-de-abastecimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smeclimatehub.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Espa\u00e7o de a\u00e7\u00e3o","item":"https:\/\/smeclimatehub.org\/pt-br\/espaco-de-acao\/"},{"@type":"ListItem","position":3,"name":"Cadeias de abastecimento"}]},{"@type":"WebSite","@id":"https:\/\/businessclimatehub.org\/es\/#website","url":"https:\/\/businessclimatehub.org\/es\/","name":"SME Climate hub","description":"","publisher":{"@id":"https:\/\/businessclimatehub.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/businessclimatehub.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/businessclimatehub.org\/es\/#organization","name":"SME Climate hub","url":"https:\/\/businessclimatehub.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/businessclimatehub.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2026\/04\/57478-SME-Climate-Hub-logo-teal_1-cropped.svg","contentUrl":"https:\/\/smeclimatehub.org\/wp-content\/uploads\/2026\/04\/57478-SME-Climate-Hub-logo-teal_1-cropped.svg","caption":"SME Climate hub"},"image":{"@id":"https:\/\/businessclimatehub.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/smeclimatehub.org\/pt-br\/wp-json\/wp\/v2\/pages\/93083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smeclimatehub.org\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/smeclimatehub.org\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/smeclimatehub.org\/pt-br\/wp-json\/wp\/v2\/users\/18450"}],"replies":[{"embeddable":true,"href":"https:\/\/smeclimatehub.org\/pt-br\/wp-json\/wp\/v2\/comments?post=93083"}],"version-history":[{"count":0,"href":"https:\/\/smeclimatehub.org\/pt-br\/wp-json\/wp\/v2\/pages\/93083\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/smeclimatehub.org\/pt-br\/wp-json\/wp\/v2\/pages\/93008"}],"wp:attachment":[{"href":"https:\/\/smeclimatehub.org\/pt-br\/wp-json\/wp\/v2\/media?parent=93083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}